{"id":26779,"date":"2019-04-06T12:48:41","date_gmt":"2019-04-06T15:48:41","guid":{"rendered":"https:\/\/www.masrojo.com.ar\/home\/?p=26779"},"modified":"2019-04-06T12:48:41","modified_gmt":"2019-04-06T15:48:41","slug":"concentrados-ante-el-canalla","status":"publish","type":"post","link":"https:\/\/www.masrojo.com.ar\/home\/2019\/04\/06\/concentrados-ante-el-canalla\/","title":{"rendered":"Concentrados ante el Canalla"},"content":{"rendered":"<p style=\"text-align: justify;\">El Cuerpo T\u00e9cnico dispuso a los 19 concentrados para disputar el \u00faltimo partido de la Superliga.<\/p>\n<p style=\"text-align: justify;\">La lista la conforman 2 arqueros, 6 defensores, 5 mediocampista y 6 atacantes.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.masrojo.com.ar\/home\/wp-content\/uploads\/Screenshot_20190406-124138_Twitter.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-26780\" src=\"https:\/\/i0.wp.com\/www.masrojo.com.ar\/home\/wp-content\/uploads\/Screenshot_20190406-124138_Twitter-1024x538.jpg?resize=1024%2C538&#038;ssl=1\" alt=\"\" width=\"1024\" height=\"538\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>El Cuerpo T\u00e9cnico dispuso a los 19 concentrados para disputar el \u00faltimo partido de la Superliga. La lista la conforman 2 arqueros, 6 defensores, 5 mediocampista y 6 atacantes. &nbsp;<\/p>\n<\/div>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"#Independiente Concentrados ante el Canalla","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4],"tags":[92,17,151],"class_list":{"0":"post-26779","1":"post","2":"type-post","3":"status-publish","4":"format-image","6":"category-actualidad","7":"tag-concentrados","8":"tag-independiente","9":"tag-rosario-central","10":"post_format-post-format-image"},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p90W9F-6XV","_links":{"self":[{"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/posts\/26779"}],"collection":[{"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/comments?post=26779"}],"version-history":[{"count":0,"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/posts\/26779\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/media?parent=26779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/categories?post=26779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/tags?post=26779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}