{"id":36194,"date":"2020-01-11T21:10:09","date_gmt":"2020-01-12T00:10:09","guid":{"rendered":"https:\/\/www.masrojo.com.ar\/home\/?p=36194"},"modified":"2020-01-11T21:10:09","modified_gmt":"2020-01-12T00:10:09","slug":"martin-campana-cuatro-anos-defendiendo-el-arco-rojo","status":"publish","type":"post","link":"https:\/\/www.masrojo.com.ar\/home\/2020\/01\/11\/martin-campana-cuatro-anos-defendiendo-el-arco-rojo\/","title":{"rendered":"Mart\u00edn Campa\u00f1a, cuatro a\u00f1os defendiendo el arco Rojo"},"content":{"rendered":"<p><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">Hace <strong>cuatro a\u00f1os<\/strong>, <strong>Mart\u00edn Campa\u00f1a<\/strong> firmaba su contrato con <\/span><span class=\"r-18u37iz\"><a class=\"css-4rbku5 css-18t94o4 css-901oao css-16my406 r-1n1174f r-1loqt21 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\" dir=\"ltr\" role=\"link\" href=\"https:\/\/twitter.com\/hashtag\/Independiente?src=hashtag_click\" data-focusable=\"true\">#Independiente<\/a><\/span><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">. El arquero sali\u00f3 campe\u00f3n de la <strong>Copa Sudamericana 2017<\/strong> en el Maracan\u00e1 frente a Flamengo y de la <strong>Suruga Bank 2018<\/strong> en Jap\u00f3n frente a Cerezo Osaka. <\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">Los n\u00fameros del uruguayo en el Rojo: En 162 partidos jugados <\/span><span class=\"css-901oao css-16my406 r-1qd0xha r-ad9z0x r-bcqeeo r-qvutc0\">recibi\u00f3 122 goles, logr\u00f3 62 v<\/span>allas invictas y ataj\u00f3 4 penales.<\/p>\n<p>Por el momento, el arquero no tiene ofertas y seguir\u00e1 en el club. Pero peder\u00e1 la capitan\u00eda, ya que <strong>Lucas<\/strong>\u00a0<strong>Pusineri<\/strong> piensa d\u00e1rsela a un futbolista de campo (<strong>Silvio Romero<\/strong> es el mayor candidato).<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Hace cuatro a\u00f1os, Mart\u00edn Campa\u00f1a firmaba su contrato con #Independiente. El arquero sali\u00f3 campe\u00f3n de la Copa Sudamericana 2017 en el Maracan\u00e1 frente a Flamengo y de la Suruga Bank 2018 en Jap\u00f3n frente a <a class=\"mh-excerpt-more\" href=\"https:\/\/www.masrojo.com.ar\/home\/2020\/01\/11\/martin-campana-cuatro-anos-defendiendo-el-arco-rojo\/\" title=\"Mart\u00edn Campa\u00f1a, cuatro a\u00f1os defendiendo el arco Rojo\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4],"tags":[108,870,869,17,237,84,497],"class_list":{"0":"post-36194","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-actualidad","7":"tag-campana","8":"tag-capitania","9":"tag-cuatro-anos","10":"tag-independiente","11":"tag-silvio-romero","12":"tag-sudamericana","13":"tag-suruga-bank"},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p90W9F-9pM","_links":{"self":[{"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/posts\/36194"}],"collection":[{"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/comments?post=36194"}],"version-history":[{"count":2,"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/posts\/36194\/revisions"}],"predecessor-version":[{"id":36202,"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/posts\/36194\/revisions\/36202"}],"wp:attachment":[{"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/media?parent=36194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/categories?post=36194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.masrojo.com.ar\/home\/wp-json\/wp\/v2\/tags?post=36194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}